{"id":271,"date":"2020-01-16T15:05:52","date_gmt":"2020-01-16T15:05:52","guid":{"rendered":"http:\/\/www.griceltravel.com\/guia-turistica-de-viajes\/?p=271"},"modified":"2020-01-16T15:07:12","modified_gmt":"2020-01-16T15:07:12","slug":"este-sera-el-ultimo-ano-en-que-los-peruanos-podran-viajar-a-europa-sin-necesidad-de-autorizacion","status":"publish","type":"post","link":"https:\/\/www.griceltravel.com\/guia-turistica-de-viajes\/este-sera-el-ultimo-ano-en-que-los-peruanos-podran-viajar-a-europa-sin-necesidad-de-autorizacion\/","title":{"rendered":"Este ser\u00e1 el \u00faltimo a\u00f1o en que los peruanos podr\u00e1n viajar a Europa sin necesidad de autorizaci\u00f3n"},"content":{"rendered":"\n<p>El<strong>&nbsp;ETIAS, o Sistema Europeo de Informaci\u00f3n y Autorizaci\u00f3n de Viajes (SEIAV) ser\u00e1 un requisito obligatorio para viajeros de sesenta nacionalidades de todo el mundo a partir de 2021<\/strong>.<\/p>\n\n\n\n<p>Este documento electr\u00f3nico -cabe precisar-&nbsp;<strong>conceder\u00e1 la entrada y libre circulaci\u00f3n entre los veintis\u00e9is pa\u00edses que conforman el \u00e1rea Schengen para estancias de hasta noventa d\u00edas<\/strong>.<\/p>\n\n\n\n<p>El requisito ser\u00e1 aplicable a los ciudadanos exentos de visado para Europa, siendo&nbsp;<strong>necesario el ETIAS para ciudadanos de Argentina, Brasil, Chile, Colombia, Costa Rica, El Salvador, Guatemala, Honduras, M\u00e9xico, Nicaragua, Panam\u00e1, Paraguay, Per\u00fa, Uruguay y Venezuela.<\/strong><\/p>\n\n\n\n<p>En cambio, no ser\u00e1 necesario para viajeros de Bolivia, Cuba o Ecuador, ya que el ETIAS es solo para los pa\u00edses que cuentan con visa Schengen y los pa\u00edses mencionados no lo tienen.<\/p>\n\n\n\n<p>El objetivo principal de ETIAS es incrementar la seguridad en los pa\u00edses Schengen \u2014entre ellos Espa\u00f1a, Italia, Francia, Alemania o Portugal \u2014 contrastando los datos de los solicitantes con varias bases de datos de seguridad como Interpol y Europol.<\/p>\n\n\n\n<p>La verificaci\u00f3n se llevar\u00e1 a cabo tras el registro de los datos personales y detalles del viaje de un solicitante \u2014sea \u00e9ste por motivos de turismo, ocio, negocios o tr\u00e1nsito.<\/p>\n\n\n\n<p>La introducci\u00f3n de ETIAS facilitar\u00e1 a las autoridades europeas la identificaci\u00f3n de personas que puedan representar una amenaza para la UE, impidi\u00e9ndoles la entrada al espacio Schengen.<\/p>\n\n\n\n<p><strong>La tramitaci\u00f3n deber\u00e1 realizarse antes de partir del pa\u00eds de origen con destino a la zona Schengen<\/strong>.<\/p>\n\n\n\n<p>En ese sentido,&nbsp;<strong>se espera que la mayor\u00eda de solicitudes sean aprobadas en tan s\u00f3lo un d\u00eda, aunque otras pudieran requerir de d\u00edas adicionales<\/strong>.<\/p>\n\n\n\n<p>Sabiendo que ETIAS entra en vigor en 2021, cabe preguntarse si aumentar\u00e1 el n\u00famero de visitantes latinoamericanos a Europa en 2020. Aunque la tramitaci\u00f3n del permiso de viaje ser\u00e1 sencilla se prev\u00e9 que un importante volumen de viajeros desee aprovechar el \u00faltimo a\u00f1o antes de la instauraci\u00f3n de este nuevo requerimiento.<\/p>\n\n\n\n<p><strong>Entre tanto, los ciudadanos de estos 15pa\u00edses de Latinoam\u00e9rica podr\u00e1n visitar Europa sin tramitar una visa Schengen.&nbsp;<\/strong>Gracias a los acuerdos vigentes, les seguir\u00e1 siendo permitida la entrada hasta finales de 2020 con la presentaci\u00f3n de su pasaporte en vigor al aterrizar.<\/p>\n\n\n\n<p>Aquellos que prefieran recorrer Europa tras la entrada en efecto de ETIAS en el a\u00f1o 2021 podr\u00e1n hacerlo tras recibir su autorizaci\u00f3n aprobada.\u00a0<strong>La validez ser\u00e1 de tres a\u00f1os o hasta que caduque el pasaporte utilizado, lo que ocurra primero<\/strong>.<\/p>\n\n\n\n<p>FUENTE: GESTI\u00d3N<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El&nbsp;ETIAS, o Sistema Europeo de Informaci\u00f3n y Autorizaci\u00f3n de Viajes (SEIAV) ser\u00e1 un requisito obligatorio para viajeros de sesenta nacionalidades de todo el mundo a partir de 2021. Este documento electr\u00f3nico -cabe precisar-&nbsp;conceder\u00e1 la entrada y libre circulaci\u00f3n entre los veintis\u00e9is pa\u00edses que conforman el \u00e1rea Schengen para estancias de hasta noventa d\u00edas. El requisito [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":272,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,25],"tags":[],"_links":{"self":[{"href":"https:\/\/www.griceltravel.com\/guia-turistica-de-viajes\/wp-json\/wp\/v2\/posts\/271"}],"collection":[{"href":"https:\/\/www.griceltravel.com\/guia-turistica-de-viajes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.griceltravel.com\/guia-turistica-de-viajes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.griceltravel.com\/guia-turistica-de-viajes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.griceltravel.com\/guia-turistica-de-viajes\/wp-json\/wp\/v2\/comments?post=271"}],"version-history":[{"count":2,"href":"https:\/\/www.griceltravel.com\/guia-turistica-de-viajes\/wp-json\/wp\/v2\/posts\/271\/revisions"}],"predecessor-version":[{"id":274,"href":"https:\/\/www.griceltravel.com\/guia-turistica-de-viajes\/wp-json\/wp\/v2\/posts\/271\/revisions\/274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.griceltravel.com\/guia-turistica-de-viajes\/wp-json\/wp\/v2\/media\/272"}],"wp:attachment":[{"href":"https:\/\/www.griceltravel.com\/guia-turistica-de-viajes\/wp-json\/wp\/v2\/media?parent=271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.griceltravel.com\/guia-turistica-de-viajes\/wp-json\/wp\/v2\/categories?post=271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.griceltravel.com\/guia-turistica-de-viajes\/wp-json\/wp\/v2\/tags?post=271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}